{"id":11561,"date":"2017-07-06T09:53:16","date_gmt":"2017-07-06T07:53:16","guid":{"rendered":"https:\/\/berlin-tagungshotels.com\/de\/?p=11561"},"modified":"2020-07-14T08:58:15","modified_gmt":"2020-07-14T06:58:15","slug":"wie-davos-zum-kurort-wurde","status":"publish","type":"post","link":"https:\/\/graubuenden-seminarhotels.ch\/de\/news\/wie-davos-zum-kurort-wurde\/","title":{"rendered":"Wie Davos zum Kurort wurde"},"content":{"rendered":"<p>1853 kam der deutsche Mediziner Alexander Spengler in den B\u00fcndner Bergort und entdeckte die heilende und gesundheitsf\u00f6rdernde Wirkung des Klimas. In dieser H\u00f6he (1560 m.\u00fc.M.) leben keine Hausstaubmilben und so kam es, dass immer mehr Lungenkranke die heilsame H\u00f6henluft nutzen wollten. Sie bekamen sogenannte \u00abLiegekuren\u00bb als Therapie verordnet. Sanatorien, Hotels und Pensionen wurden gebaut und Davos wurde als Luftkurort weltber\u00fchmt.<\/p>\n<h2>Der Kurort Davos<\/h2>\n<p>Auch der Schriftsteller Thomas Mann besuchte seine kranke Gattin in Davos. Inspiriert durch ihre Briefe und Erz\u00e4hlungen entstand der Roman \u00abDer Zauberberg\u00bb, der vom Leben in den Sanatorien handelt.<\/p>\n<p>Sp\u00e4ter wurde das SIAF \u2013 Schweizerische Institut f\u00fcr Allergie- und Asthmaforschung gegr\u00fcndet. W\u00e4hrend sich das Institut fr\u00fcher haupts\u00e4chlich mit Tuberkuloseerkrankungen besch\u00e4ftigte, steht heute die Forschung von allergischen Krankheiten im Vordergrund. So wurde \u00fcber die Zeit Davos zum Kurort.<\/p>","protected":false},"excerpt":{"rendered":"<p>1853 kam der deutsche Mediziner Alexander Spengler in den B\u00fcndner Bergort und entdeckte die heilende und gesundheitsf\u00f6rdernde Wirkung des Klimas. In dieser H\u00f6he (1560 m.\u00fc.M.) leben keine Hausstaubmilben und so kam es, dass immer mehr Lungenkranke die heilsame H\u00f6henluft nutzen wollten. Sie bekamen sogenannte \u00abLiegekuren\u00bb als Therapie verordnet. Sanatorien, Hotels und Pensionen wurden gebaut und [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":20654,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.3 (Yoast SEO v20.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Wie Davos zum Kurort wurde | MICE Service Group | Seminarhotels in Graub\u00fcnden<\/title>\n<meta name=\"description\" content=\"Wie Davos zum Kurort wurde? Der Mediziner Alexander Spengler kam 1853 in den B\u00fcndner Bergort und entdeckte die heilende Wirkung des Klimas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/graubuenden-seminarhotels.ch\/de\/news\/wie-davos-zum-kurort-wurde\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wie Davos zum Kurort wurde\" \/>\n<meta property=\"og:description\" content=\"Wie Davos zum Kurort wurde? Der Mediziner Alexander Spengler kam 1853 in den B\u00fcndner Bergort und entdeckte die heilende Wirkung des Klimas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/graubuenden-seminarhotels.ch\/de\/news\/wie-davos-zum-kurort-wurde\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-06T07:53:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-14T06:58:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/graubuenden-seminarhotels.ch\/wp-content\/uploads\/2017\/07\/blumenwiese-bett-liegekur-davos-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mandy Weinand\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mandy Weinand\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/graubuenden-seminarhotels.ch\/de\/news\/wie-davos-zum-kurort-wurde\/\",\"url\":\"https:\/\/graubuenden-seminarhotels.ch\/de\/news\/wie-davos-zum-kurort-wurde\/\",\"name\":\"Wie Davos zum Kurort wurde | MICE Service Group\",\"isPartOf\":{\"@id\":\"https:\/\/genf-seminarhotels.ch\/de\/#website\"},\"datePublished\":\"2017-07-06T07:53:16+00:00\",\"dateModified\":\"2020-07-14T06:58:15+00:00\",\"author\":{\"@id\":\"https:\/\/genf-seminarhotels.ch\/de\/#\/schema\/person\/68a753e2d9667d03770466eea9649fe2\"},\"description\":\"Wie Davos zum Kurort wurde? Der Mediziner Alexander Spengler kam 1853 in den B\u00fcndner Bergort und entdeckte die heilende Wirkung des Klimas.\",\"breadcrumb\":{\"@id\":\"https:\/\/graubuenden-seminarhotels.ch\/de\/news\/wie-davos-zum-kurort-wurde\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/graubuenden-seminarhotels.ch\/de\/news\/wie-davos-zum-kurort-wurde\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/graubuenden-seminarhotels.ch\/de\/news\/wie-davos-zum-kurort-wurde\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/genf-seminarhotels.ch\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"News\",\"item\":\"https:\/\/graubuenden-seminarhotels.ch\/de\/news\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wie Davos zum Kurort wurde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/genf-seminarhotels.ch\/de\/#website\",\"url\":\"https:\/\/genf-seminarhotels.ch\/de\/\",\"name\":\"graubuenden-seminarhotels.ch\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/genf-seminarhotels.ch\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/genf-seminarhotels.ch\/de\/#\/schema\/person\/68a753e2d9667d03770466eea9649fe2\",\"name\":\"Mandy Weinand\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/genf-seminarhotels.ch\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/graubuenden-seminarhotels.ch\/wp-content\/wphb-cache\/gravatar\/693\/693ba2c33a7477a8ce804f5f29c6efcex96.jpg\",\"contentUrl\":\"https:\/\/graubuenden-seminarhotels.ch\/wp-content\/wphb-cache\/gravatar\/693\/693ba2c33a7477a8ce804f5f29c6efcex96.jpg\",\"caption\":\"Mandy Weinand\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Wie Davos zum Kurort wurde | MICE Service Group | Seminarhotels in Graub\u00fcnden","description":"Wie Davos zum Kurort wurde? Der Mediziner Alexander Spengler kam 1853 in den B\u00fcndner Bergort und entdeckte die heilende Wirkung des Klimas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/graubuenden-seminarhotels.ch\/de\/news\/wie-davos-zum-kurort-wurde\/","og_locale":"de_DE","og_type":"article","og_title":"Wie Davos zum Kurort wurde","og_description":"Wie Davos zum Kurort wurde? Der Mediziner Alexander Spengler kam 1853 in den B\u00fcndner Bergort und entdeckte die heilende Wirkung des Klimas.","og_url":"https:\/\/graubuenden-seminarhotels.ch\/de\/news\/wie-davos-zum-kurort-wurde\/","article_published_time":"2017-07-06T07:53:16+00:00","article_modified_time":"2020-07-14T06:58:15+00:00","og_image":[{"width":"1800","height":"1200","url":"https:\/\/graubuenden-seminarhotels.ch\/wp-content\/uploads\/2017\/07\/blumenwiese-bett-liegekur-davos-.jpg","type":"image\/jpeg"}],"author":"Mandy Weinand","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Mandy Weinand","Gesch\u00e4tzte Lesezeit":"1 Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/graubuenden-seminarhotels.ch\/de\/news\/wie-davos-zum-kurort-wurde\/","url":"https:\/\/graubuenden-seminarhotels.ch\/de\/news\/wie-davos-zum-kurort-wurde\/","name":"Wie Davos zum Kurort wurde | MICE Service Group","isPartOf":{"@id":"https:\/\/genf-seminarhotels.ch\/de\/#website"},"datePublished":"2017-07-06T07:53:16+00:00","dateModified":"2020-07-14T06:58:15+00:00","author":{"@id":"https:\/\/genf-seminarhotels.ch\/de\/#\/schema\/person\/68a753e2d9667d03770466eea9649fe2"},"description":"Wie Davos zum Kurort wurde? Der Mediziner Alexander Spengler kam 1853 in den B\u00fcndner Bergort und entdeckte die heilende Wirkung des Klimas.","breadcrumb":{"@id":"https:\/\/graubuenden-seminarhotels.ch\/de\/news\/wie-davos-zum-kurort-wurde\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/graubuenden-seminarhotels.ch\/de\/news\/wie-davos-zum-kurort-wurde\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/graubuenden-seminarhotels.ch\/de\/news\/wie-davos-zum-kurort-wurde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/genf-seminarhotels.ch\/de\/"},{"@type":"ListItem","position":2,"name":"News","item":"https:\/\/graubuenden-seminarhotels.ch\/de\/news\/"},{"@type":"ListItem","position":3,"name":"Wie Davos zum Kurort wurde"}]},{"@type":"WebSite","@id":"https:\/\/genf-seminarhotels.ch\/de\/#website","url":"https:\/\/genf-seminarhotels.ch\/de\/","name":"graubuenden-seminarhotels.ch","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/genf-seminarhotels.ch\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/genf-seminarhotels.ch\/de\/#\/schema\/person\/68a753e2d9667d03770466eea9649fe2","name":"Mandy Weinand","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/genf-seminarhotels.ch\/de\/#\/schema\/person\/image\/","url":"https:\/\/graubuenden-seminarhotels.ch\/wp-content\/wphb-cache\/gravatar\/693\/693ba2c33a7477a8ce804f5f29c6efcex96.jpg","contentUrl":"https:\/\/graubuenden-seminarhotels.ch\/wp-content\/wphb-cache\/gravatar\/693\/693ba2c33a7477a8ce804f5f29c6efcex96.jpg","caption":"Mandy Weinand"}}]}},"_links":{"self":[{"href":"https:\/\/graubuenden-seminarhotels.ch\/de\/wp-json\/wp\/v2\/posts\/11561"}],"collection":[{"href":"https:\/\/graubuenden-seminarhotels.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/graubuenden-seminarhotels.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/graubuenden-seminarhotels.ch\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/graubuenden-seminarhotels.ch\/de\/wp-json\/wp\/v2\/comments?post=11561"}],"version-history":[{"count":0,"href":"https:\/\/graubuenden-seminarhotels.ch\/de\/wp-json\/wp\/v2\/posts\/11561\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/graubuenden-seminarhotels.ch\/de\/wp-json\/wp\/v2\/media\/20654"}],"wp:attachment":[{"href":"https:\/\/graubuenden-seminarhotels.ch\/de\/wp-json\/wp\/v2\/media?parent=11561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}